{"id":217,"count":1,"description":"","link":"https:\/\/expomon.es\/ca\/tag\/sant-antoni\/","name":"sant antoni","slug":"sant-antoni","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expomon.es\/ca\/tag\/sant-antoni\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/tag\\\/sant-antoni\\\/#listItem\",\"name\":\"sant antoni\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/tag\\\/sant-antoni\\\/#listItem\",\"position\":2,\"name\":\"sant antoni\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/#collectionpage\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/\",\"name\":\"sant antoni | Expomon\",\"inLanguage\":\"ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#organization\",\"name\":\"Expomon Produccions i Muntatges SL\",\"description\":\"Producci\\u00f3n y montaje de exposiciones\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"telephone\":\"+34938306646\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expomon.es\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo2.png\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/#organizationLogo\",\"width\":390,\"height\":96},\"image\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/217\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.twitter.com\\\/expomon\",\"https:\\\/\\\/www.instagram.com\\\/expomon\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/expomon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCImS0rmYTDOlJAxKWAd7QCQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/9385691\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"name\":\"Expomon\",\"description\":\"Producci\\u00f3n y montaje de exposiciones\",\"inLanguage\":\"ca\",\"publisher\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"sant antoni | Expomon","description":"","canonical_url":"https:\/\/expomon.es\/ca\/tag\/sant-antoni\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/#listItem","position":1,"name":"Home","item":"https:\/\/expomon.es\/ca\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/tag\/sant-antoni\/#listItem","name":"sant antoni"}},{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/tag\/sant-antoni\/#listItem","position":2,"name":"sant antoni","previousItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/#collectionpage","url":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/","name":"sant antoni | Expomon","inLanguage":"ca","isPartOf":{"@id":"https:\/\/expomon.es\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/expomon.es\/ca\/#organization","name":"Expomon Produccions i Muntatges SL","description":"Producci\u00f3n y montaje de exposiciones","url":"https:\/\/expomon.es\/ca\/","telephone":"+34938306646","logo":{"@type":"ImageObject","url":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/03\/logo2.png","@id":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/#organizationLogo","width":390,"height":96},"image":{"@id":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217\/#organizationLogo"},"sameAs":["https:\/\/www.twitter.com\/expomon","https:\/\/www.instagram.com\/expomon\/","https:\/\/www.pinterest.es\/expomon\/","https:\/\/www.youtube.com\/channel\/UCImS0rmYTDOlJAxKWAd7QCQ","https:\/\/www.linkedin.com\/company\/9385691\/"]},{"@type":"WebSite","@id":"https:\/\/expomon.es\/ca\/#website","url":"https:\/\/expomon.es\/ca\/","name":"Expomon","description":"Producci\u00f3n y montaje de exposiciones","inLanguage":"ca","publisher":{"@id":"https:\/\/expomon.es\/ca\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/posts?tags=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}