{"id":11792,"date":"2019-02-25T11:45:34","date_gmt":"2019-02-25T10:45:34","guid":{"rendered":"https:\/\/expomon.es\/?p=11546"},"modified":"2019-02-25T11:45:34","modified_gmt":"2019-02-25T10:45:34","slug":"herois-ocults-arriba-a-lorca","status":"publish","type":"post","link":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/","title":{"rendered":"Herois Ocults arriba a Lorca"},"content":{"rendered":"<p>Del 15 de febrer al 3 de mar\u00e7 els habitants de Lorca i rodalies podran descobrir als Herois que ens acompanyen en la nostra vida quotidiana a trav\u00e9s de l&#8217;exposici\u00f3 itinerant Herois Ocults. Invents genials, objectes quotidians. Qu\u00e8 fa que un objecte quotidi\u00e0 esdevingui un heroi ocult? Deu ser alguna cosa relacionada amb una idea enginyosa, per\u00f2 f\u00e0cilment comprensible. Els &#8220;herois ocults&#8221; s\u00f3n objectes que han estat fabricats milions de vegades, per\u00f2 que segueixen sent indispensables en el dia a dia. S\u00f3n objectes que han demostrat la seva v\u00e0lua una i altra vegada i que, en ess\u00e8ncia, han rom\u00e0s inalterables durant d\u00e8cades o, dit d&#8217;una altra manera, s\u00f3n cl\u00e0ssics quotidians. Amb els objectes, les imatges i els v\u00eddeos que es presenten en aquesta exposici\u00f3 pretenem mostrar quatre aspectes particularment interessants: La innovaci\u00f3: la fascinant hist\u00f2ria de la invenci\u00f3 d&#8217;aquests objectes. La producci\u00f3: les condicions t\u00e8cniques de la seva reeixida fabricaci\u00f3 a gran escala. L&#8217;evoluci\u00f3: el seu desenvolupament hist\u00f2ric i la sorprenent diversitat de models i variacions que han generat. La inspiraci\u00f3: la seva est\u00e8tica, que segueix inspirant el treball d&#8217;artistes i dissenyadors. L&#8217;Obra Social &#8220;la Caixa&#8221; presenta l&#8217;exposici\u00f3 itinerant &#8220;Herois ocults. Invents genials. Objectes quotidians &#8220;, una mostra en qu\u00e8 hi ha molt per descobrir.<\/p>\n<p><a href=\"https:\/\/expomon.es\/ca\/portfolio\/herois-ocults\/\">Recorregut virtual<\/a><\/p>\n<p><a href=\"https:\/\/www.elcatalan.es\/heroes-ocultos-inventos-geniales-objetos-cotidianos-lorca\">M\u00e9s informaci\u00f3<\/a><\/p>\n<p>&nbsp;    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 15 de febrer al 3 de mar\u00e7 els habitants de Lorca i rodalies podran descobrir als Herois que ens acompanyen en la nostra vida quotidiana a trav\u00e9s de l&#8217;exposici\u00f3 itinerant Herois Ocults. Invents genials, objectes quotidians. Qu\u00e8 fa que un objecte quotidi\u00e0 esdevingui un heroi ocult? Deu ser alguna cosa relacionada amb una idea  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":11619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[124,274],"tags":[283,320,321],"class_list":["post-11792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expomon-ca","category-itinerancies","tag-exposicio-itinerant","tag-herois-ocults-lorca","tag-lorca-cultura-ca"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Expomon\"\/>\n\t<meta name=\"keywords\" content=\"exposici\u00f3 itinerant,herois ocults lorca,lorca cultura\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"ca_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Expomon | Producci\u00f3n y montaje de exposiciones\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Herois Ocults arriba a Lorca | Expomon\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-25T10:45:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-25T10:45:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/expomon\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#article\",\"name\":\"Herois Ocults arriba a Lorca | Expomon\",\"headline\":\"Herois Ocults arriba a Lorca\",\"author\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expomon.es\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/IMG_4364.jpeg\",\"width\":2048,\"height\":1536},\"datePublished\":\"2019-02-25T11:45:34+01:00\",\"dateModified\":\"2019-02-25T11:45:34+01:00\",\"inLanguage\":\"ca\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#webpage\"},\"articleSection\":\"Expomon, itinerancies, exposici\\u00f3 itinerant, herois ocults lorca, Lorca cultura, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/#listItem\",\"name\":\"Expomon\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/#listItem\",\"position\":2,\"name\":\"Expomon\",\"item\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/itinerancies\\\/#listItem\",\"name\":\"itinerancies\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/itinerancies\\\/#listItem\",\"position\":3,\"name\":\"itinerancies\",\"item\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/itinerancies\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#listItem\",\"name\":\"Herois Ocults arriba a Lorca\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/#listItem\",\"name\":\"Expomon\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#listItem\",\"position\":4,\"name\":\"Herois Ocults arriba a Lorca\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/category\\\/expomon-ca\\\/itinerancies\\\/#listItem\",\"name\":\"itinerancies\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#organization\",\"name\":\"Expomon Produccions i Muntatges SL\",\"description\":\"Producci\\u00f3n y montaje de exposiciones\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"telephone\":\"+34938306646\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expomon.es\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo2.png\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#organizationLogo\",\"width\":390,\"height\":96},\"image\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.twitter.com\\\/expomon\",\"https:\\\/\\\/www.instagram.com\\\/expomon\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/expomon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCImS0rmYTDOlJAxKWAd7QCQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/9385691\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/author\\\/admin\\\/\",\"name\":\"Expomon\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccde44166641a6430f4ce5723c903db8f6bc6c858910435a908cf3f1e73d4d31?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Expomon\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#webpage\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/\",\"name\":\"Herois Ocults arriba a Lorca | Expomon\",\"inLanguage\":\"ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expomon.es\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/IMG_4364.jpeg\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#mainImage\",\"width\":2048,\"height\":1536},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/herois-ocults-arriba-a-lorca\\\/#mainImage\"},\"datePublished\":\"2019-02-25T11:45:34+01:00\",\"dateModified\":\"2019-02-25T11:45:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/expomon.es\\\/ca\\\/\",\"name\":\"Expomon\",\"description\":\"Producci\\u00f3n y montaje de exposiciones\",\"inLanguage\":\"ca\",\"publisher\":{\"@id\":\"https:\\\/\\\/expomon.es\\\/ca\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Herois Ocults arriba a Lorca | Expomon","description":"","canonical_url":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/","robots":"max-image-preview:large","keywords":"exposici\u00f3 itinerant,herois ocults lorca,lorca cultura","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#article","name":"Herois Ocults arriba a Lorca | Expomon","headline":"Herois Ocults arriba a Lorca","author":{"@id":"https:\/\/expomon.es\/ca\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/expomon.es\/ca\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg","width":2048,"height":1536},"datePublished":"2019-02-25T11:45:34+01:00","dateModified":"2019-02-25T11:45:34+01:00","inLanguage":"ca","mainEntityOfPage":{"@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#webpage"},"isPartOf":{"@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#webpage"},"articleSection":"Expomon, itinerancies, exposici\u00f3 itinerant, herois ocults lorca, Lorca cultura, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/#listItem","position":1,"name":"Home","item":"https:\/\/expomon.es\/ca\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/#listItem","name":"Expomon"}},{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/#listItem","position":2,"name":"Expomon","item":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/itinerancies\/#listItem","name":"itinerancies"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/itinerancies\/#listItem","position":3,"name":"itinerancies","item":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/itinerancies\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#listItem","name":"Herois Ocults arriba a Lorca"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/#listItem","name":"Expomon"}},{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#listItem","position":4,"name":"Herois Ocults arriba a Lorca","previousItem":{"@type":"ListItem","@id":"https:\/\/expomon.es\/ca\/category\/expomon-ca\/itinerancies\/#listItem","name":"itinerancies"}}]},{"@type":"Organization","@id":"https:\/\/expomon.es\/ca\/#organization","name":"Expomon Produccions i Muntatges SL","description":"Producci\u00f3n y montaje de exposiciones","url":"https:\/\/expomon.es\/ca\/","telephone":"+34938306646","logo":{"@type":"ImageObject","url":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/03\/logo2.png","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#organizationLogo","width":390,"height":96},"image":{"@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#organizationLogo"},"sameAs":["https:\/\/www.twitter.com\/expomon","https:\/\/www.instagram.com\/expomon\/","https:\/\/www.pinterest.es\/expomon\/","https:\/\/www.youtube.com\/channel\/UCImS0rmYTDOlJAxKWAd7QCQ","https:\/\/www.linkedin.com\/company\/9385691\/"]},{"@type":"Person","@id":"https:\/\/expomon.es\/ca\/author\/admin\/#author","url":"https:\/\/expomon.es\/ca\/author\/admin\/","name":"Expomon","image":{"@type":"ImageObject","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ccde44166641a6430f4ce5723c903db8f6bc6c858910435a908cf3f1e73d4d31?s=96&d=mm&r=g","width":96,"height":96,"caption":"Expomon"}},{"@type":"WebPage","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#webpage","url":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/","name":"Herois Ocults arriba a Lorca | Expomon","inLanguage":"ca","isPartOf":{"@id":"https:\/\/expomon.es\/ca\/#website"},"breadcrumb":{"@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#breadcrumblist"},"author":{"@id":"https:\/\/expomon.es\/ca\/author\/admin\/#author"},"creator":{"@id":"https:\/\/expomon.es\/ca\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg","@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#mainImage","width":2048,"height":1536},"primaryImageOfPage":{"@id":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/#mainImage"},"datePublished":"2019-02-25T11:45:34+01:00","dateModified":"2019-02-25T11:45:34+01:00"},{"@type":"WebSite","@id":"https:\/\/expomon.es\/ca\/#website","url":"https:\/\/expomon.es\/ca\/","name":"Expomon","description":"Producci\u00f3n y montaje de exposiciones","inLanguage":"ca","publisher":{"@id":"https:\/\/expomon.es\/ca\/#organization"}}]},"og:locale":"ca_ES","og:site_name":"Expomon | Producci\u00f3n y montaje de exposiciones","og:type":"article","og:title":"Herois Ocults arriba a Lorca | Expomon","og:url":"https:\/\/expomon.es\/ca\/herois-ocults-arriba-a-lorca\/","og:image":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg","og:image:secure_url":"https:\/\/expomon.es\/wp-content\/uploads\/2019\/02\/IMG_4364.jpeg","og:image:width":2048,"og:image:height":1536,"article:published_time":"2019-02-25T10:45:34+00:00","article:modified_time":"2019-02-25T10:45:34+00:00","article:publisher":"https:\/\/www.facebook.com\/expomon"},"aioseo_meta_data":{"post_id":"11792","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 09:50:27","updated":"2025-06-13 22:56:42","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/posts\/11792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/comments?post=11792"}],"version-history":[{"count":0,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/posts\/11792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/media\/11619"}],"wp:attachment":[{"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/media?parent=11792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/categories?post=11792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expomon.es\/ca\/wp-json\/wp\/v2\/tags?post=11792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}